{"id":316,"count":1,"description":"Alquileres vacacionales en San Juan del Sur, Nicaragua.","link":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/","name":"Los miradores de Nacascolo","slug":"los-miradores-de-nacascolo-nicaragua","taxonomy":"property_area","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur\" \/>\n<meta property=\"og:description\" content=\"Alquileres vacacionales en San Juan del Sur, Nicaragua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/\" \/>\n<meta property=\"og:site_name\" content=\"Long Term &amp; Vacation Rentals in San Juan del Sur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/property_area\\\/los-miradores-de-nacascolo-nicaragua\\\/\",\"url\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/property_area\\\/los-miradores-de-nacascolo-nicaragua\\\/\",\"name\":\"Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/property_area\\\/los-miradores-de-nacascolo-nicaragua\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/property_area\\\/los-miradores-de-nacascolo-nicaragua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los miradores de Nacascolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/\",\"name\":\"Long Term &amp; Vacation Rentals in San Juan del Sur\",\"description\":\"Sol &amp; Playa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/","og_locale":"es_ES","og_type":"article","og_title":"Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur","og_description":"Alquileres vacacionales en San Juan del Sur, Nicaragua.","og_url":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/","og_site_name":"Long Term &amp; Vacation Rentals in San Juan del Sur","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/","url":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/","name":"Los miradores de Nacascolo - Long Term &amp; Vacation Rentals in San Juan del Sur","isPartOf":{"@id":"https:\/\/solplayarentals.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/solplayarentals.com\/es\/property_area\/los-miradores-de-nacascolo-nicaragua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/solplayarentals.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los miradores de Nacascolo"}]},{"@type":"WebSite","@id":"https:\/\/solplayarentals.com\/es\/#website","url":"https:\/\/solplayarentals.com\/es\/","name":"Long Term &amp; Vacation Rentals in San Juan del Sur","description":"Sol &amp; Playa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplayarentals.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_area\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_area"}],"about":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/taxonomies\/property_area"}],"wp:post_type":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/estate_property?property_area=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}