{"id":20967,"date":"2022-12-06T12:57:28","date_gmt":"2022-12-06T18:57:28","guid":{"rendered":"https:\/\/solplayarentals.com\/san-juan-del-sur\/villa-molly-2-2\/"},"modified":"2023-04-03T18:41:16","modified_gmt":"2023-04-04T00:41:16","slug":"villa-molly-2","status":"publish","type":"estate_property","link":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/","title":{"rendered":"Villa Molly #2"},"content":{"rendered":"\n<p>Ubicada en el centro, a <strong>3 cuadras de la playa<\/strong>. Capacidad para 6 personas m\u00e1x.<\/p>\n\n\n\n<p>\u00a1Casa Villa Molly #2 es encantadora! Es un <strong>alquiler vacacional en San Juan del Sur<\/strong> perfecto para familias, grupos de amigos y parejas que buscan un refugio de lujo.<\/p>\n\n\n\n<p>Esta es una casa muy bonita en la ciudad, escondida en una parte <strong>tranquila y pac\u00edfica de San Juan del Sur<\/strong>, pero a poca distancia de todo, y a <strong>2 minutos a pie de la playa<\/strong>. Todos los servicios en el escal\u00f3n de tu puerta. Vecindario seguro y protegido, con seguridad in sitio. <strong>No hay necesidad de un coche<\/strong>.<\/p>\n\n\n\n<p>Cuenta con <strong>cocina equipada<\/strong> con todos los electrodom\u00e9sticos modernos, utensilios y vajilla. Incluye horno, 6 fogones de gas, tostadora y hervidor de agua.&nbsp;La sala de estar es de planta abierta y ofrece un comedor completo.&nbsp;<\/p>\n\n\n\n<p>Los <strong>3 amplios dormitorios en suite<\/strong> son espaciosos y est\u00e1n todos equipados con <strong>aire acondicionado<\/strong> y ventiladores de techo, con pantallas en todas las ventanas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>La propiedad <strong>cuenta con lavander\u00eda<\/strong> bajo petici\u00f3n por un cargo, excepto en alquileres de larga duraci\u00f3n de 28 d\u00edas o m\u00e1s sin costo adicional, ya que la electricidad se cobra por separado.<\/p>\n\n\n\n<p>Se proporciona limpieza si es necesario por un costo adicional.<\/p>\n\n\n\n<p>Incluye 20 kilowatts por d\u00eda ($1 por kilowatt extra).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicada en el centro, a 3 cuadras de la playa. Capacidad para 6 personas m\u00e1x. \u00a1Casa Villa Molly #2 es encantadora! Es un alquiler vacacional en San Juan del Sur perfecto para familias, grupos de amigos y parejas que buscan un refugio de lujo. Esta es una casa muy bonita en la ciudad, escondida en una parte tranquila y pac\u00edfica de San Juan del &#8230;<\/p>\n","protected":false},"featured_media":20984,"template":"","property_category":[309],"property_action_category":[215],"property_city":[225],"property_area":[],"property_county_state":[305],"property_features":[301,299,263,292,261,300,295,297,298,302,304],"property_status":[],"class_list":["post-20967","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-villas","property_action_category-rentas-vacacionales","property_city-san-juan-del-sur-nicaragua","property_county_state-rivas-nicaragua","property_features-agua-caliente","property_features-aire-acondicionado","property_features-cocina-equipada","property_features-detalles-exteriores","property_features-detalles-interiores","property_features-electricidad","property_features-piscina","property_features-seguridad","property_features-utilidades","property_features-ventilacion","property_features-internet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Molly #2 - Long Term &amp; Vacation Rentals in San Juan del Sur<\/title>\n<meta name=\"description\" content=\"Alquiler de Casas de Vacaciones en San Juan del Sur, NI. Betzy Barboza: Agente Inmobiliaria en San Juan del Sur, Alquileres Vacacionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2600\ufe0f Casas Vacacionales \u27a4 Reserva ahora en San Juan del Sur \ud83c\udfd6\ufe0f\" \/>\n<meta property=\"og:description\" content=\"Alquiler de Casas Vacacionales en San Juan del Sur \u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Long Term &amp; Vacation Rentals in San Juan del Sur\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-04T00:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solplayarentals.com\/wp-content\/uploads\/2022\/12\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/\",\"url\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/\",\"name\":\"Villa Molly #2 - Long Term &amp; Vacation Rentals in San Juan del Sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solplayarentals.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg\",\"datePublished\":\"2022-12-06T18:57:28+00:00\",\"dateModified\":\"2023-04-04T00:41:16+00:00\",\"description\":\"Alquiler de Casas de Vacaciones en San Juan del Sur, NI. Betzy Barboza: Agente Inmobiliaria en San Juan del Sur, Alquileres Vacacionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solplayarentals.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg\",\"contentUrl\":\"https:\\\/\\\/solplayarentals.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Villa Molly 2- Sol & Playa Vacation Rentals in Nicaragua\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/villa-molly-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/san-juan-del-sur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa Molly #2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/\",\"name\":\"Long Term &amp; Vacation Rentals in San Juan del Sur\",\"description\":\"Sol &amp; Playa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solplayarentals.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Molly #2 - Long Term &amp; Vacation Rentals in San Juan del Sur","description":"Alquiler de Casas de Vacaciones en San Juan del Sur, NI. Betzy Barboza: Agente Inmobiliaria en San Juan del Sur, Alquileres Vacacionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u2600\ufe0f Casas Vacacionales \u27a4 Reserva ahora en San Juan del Sur \ud83c\udfd6\ufe0f","og_description":"Alquiler de Casas Vacacionales en San Juan del Sur \u2714","og_url":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/","og_site_name":"Long Term &amp; Vacation Rentals in San Juan del Sur","article_modified_time":"2023-04-04T00:41:16+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/solplayarentals.com\/wp-content\/uploads\/2022\/12\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/","url":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/","name":"Villa Molly #2 - Long Term &amp; Vacation Rentals in San Juan del Sur","isPartOf":{"@id":"https:\/\/solplayarentals.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/#primaryimage"},"image":{"@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/#primaryimage"},"thumbnailUrl":"https:\/\/solplayarentals.com\/wp-content\/uploads\/2022\/12\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg","datePublished":"2022-12-06T18:57:28+00:00","dateModified":"2023-04-04T00:41:16+00:00","description":"Alquiler de Casas de Vacaciones en San Juan del Sur, NI. Betzy Barboza: Agente Inmobiliaria en San Juan del Sur, Alquileres Vacacionales.","breadcrumb":{"@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/#primaryimage","url":"https:\/\/solplayarentals.com\/wp-content\/uploads\/2022\/12\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg","contentUrl":"https:\/\/solplayarentals.com\/wp-content\/uploads\/2022\/12\/Villa-Molly-2-Sol-Playa-Vacation-Rentals-in-Nicaragua-1.jpg","width":1200,"height":800,"caption":"Villa Molly 2- Sol & Playa Vacation Rentals in Nicaragua"},{"@type":"BreadcrumbList","@id":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/villa-molly-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/solplayarentals.com\/es\/"},{"@type":"ListItem","position":2,"name":"Propiedades","item":"https:\/\/solplayarentals.com\/es\/san-juan-del-sur\/"},{"@type":"ListItem","position":3,"name":"Villa Molly #2"}]},{"@type":"WebSite","@id":"https:\/\/solplayarentals.com\/es\/#website","url":"https:\/\/solplayarentals.com\/es\/","name":"Long Term &amp; Vacation Rentals in San Juan del Sur","description":"Sol &amp; Playa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplayarentals.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/estate_property\/20967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/types\/estate_property"}],"version-history":[{"count":1,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/estate_property\/20967\/revisions"}],"predecessor-version":[{"id":23159,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/estate_property\/20967\/revisions\/23159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/media\/20984"}],"wp:attachment":[{"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/media?parent=20967"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_category?post=20967"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_action_category?post=20967"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_city?post=20967"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_area?post=20967"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_county_state?post=20967"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_features?post=20967"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/solplayarentals.com\/es\/wp-json\/wp\/v2\/property_status?post=20967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}